{"id":3104,"date":"2019-06-21T09:12:28","date_gmt":"2019-06-21T07:12:28","guid":{"rendered":"http:\/\/20.77.7.22\/shop\/senza%20categoria\/umgang-mit-suchtgefahrdeten-mitarbeitenden\/"},"modified":"2025-06-05T10:22:09","modified_gmt":"2025-06-05T08:22:09","slug":"rapporti-con-collaboratori-a-rischio-di-dipendenza","status":"publish","type":"product","link":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/","title":{"rendered":"Rapporti con i collaboratori a rischio di dipendenza"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>L\u2019identificazione e il supporto dei collaboratori a rischio di dipendenza \u00e8 quindi una parte essenziale della prevenzione sanitaria aziendale. Ma come reagire se si sospetta che un collaboratore abbia problemi di dipendenza? In questo seminario, i partecipanti apprenderanno a conoscere i meccanismi fondamentali della dipendenza, i rischi e le conseguenze dell\u2019abuso di sostanze e delle dipendenze. Scopriranno inoltre quali segni comportamentali possono permettere di identificare un potenziale problema di dipendenza e quale procedura \u00e8 appropriata per supportare i collaboratori a rischio di dipendenza, o gi\u00e0 dipendenti, nell\u2019ambito delle possibilit\u00e0 aziendali.<\/p>\n","protected":false},"featured_media":2253,"template":"","meta":[],"product_brand":[],"product_cat":[128],"product_tag":[],"class_list":{"0":"post-3104","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-prodotti-lyra-wellbeing-academy","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rapporti con i collaboratori a rischio di dipendenza | Lyra Schweiz GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapporti con i collaboratori a rischio di dipendenza | Lyra Schweiz GmbH\" \/>\n<meta property=\"og:description\" content=\"L\u2019identificazione e il supporto dei collaboratori a rischio di dipendenza \u00e8 quindi una parte essenziale della prevenzione sanitaria aziendale. Ma come reagire se si sospetta che un collaboratore abbia problemi di dipendenza? In questo seminario, i partecipanti apprenderanno a conoscere i meccanismi fondamentali della dipendenza, i rischi e le conseguenze dell\u2019abuso di sostanze e delle dipendenze. Scopriranno inoltre quali segni comportamentali possono permettere di identificare un potenziale problema di dipendenza e quale procedura \u00e8 appropriata per supportare i collaboratori a rischio di dipendenza, o gi\u00e0 dipendenti, nell\u2019ambito delle possibilit\u00e0 aziendali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyra Schweiz GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T08:22:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lyrawellbeing.ch\/wp-content\/uploads\/2019\/06\/istockphoto-880860758-2048x2048.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"932\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/\",\"url\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/\",\"name\":\"Rapporti con i collaboratori a rischio di dipendenza | Lyra Schweiz GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyrawellbeing.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/istockphoto-880860758-2048x2048.jpg\",\"datePublished\":\"2019-06-21T07:12:28+00:00\",\"dateModified\":\"2025-06-05T08:22:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/#primaryimage\",\"url\":\"\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/istockphoto-880860758-2048x2048.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/istockphoto-880860758-2048x2048.jpg\",\"width\":1400,\"height\":932,\"caption\":\"Alcoholism or drinking problem concept. Alcoholic with vodka bottle on table. Man and alcohol late at night. Drunk at work or in home office.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/rapporti-con-collaboratori-a-rischio-di-dipendenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lyrawellbeing.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lyrawellbeing.ch\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rapporti con i collaboratori a rischio di dipendenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyrawellbeing.ch\\\/#website\",\"url\":\"https:\\\/\\\/lyrawellbeing.ch\\\/\",\"name\":\"Lyra Schweiz GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyrawellbeing.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapporti con i collaboratori a rischio di dipendenza | Lyra Schweiz GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/","og_locale":"it_IT","og_type":"article","og_title":"Rapporti con i collaboratori a rischio di dipendenza | Lyra Schweiz GmbH","og_description":"L\u2019identificazione e il supporto dei collaboratori a rischio di dipendenza \u00e8 quindi una parte essenziale della prevenzione sanitaria aziendale. Ma come reagire se si sospetta che un collaboratore abbia problemi di dipendenza? In questo seminario, i partecipanti apprenderanno a conoscere i meccanismi fondamentali della dipendenza, i rischi e le conseguenze dell\u2019abuso di sostanze e delle dipendenze. Scopriranno inoltre quali segni comportamentali possono permettere di identificare un potenziale problema di dipendenza e quale procedura \u00e8 appropriata per supportare i collaboratori a rischio di dipendenza, o gi\u00e0 dipendenti, nell\u2019ambito delle possibilit\u00e0 aziendali.","og_url":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/","og_site_name":"Lyra Schweiz GmbH","article_modified_time":"2025-06-05T08:22:09+00:00","og_image":[{"width":1400,"height":932,"url":"https:\/\/www.lyrawellbeing.ch\/wp-content\/uploads\/2019\/06\/istockphoto-880860758-2048x2048.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/","url":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/","name":"Rapporti con i collaboratori a rischio di dipendenza | Lyra Schweiz GmbH","isPartOf":{"@id":"https:\/\/lyrawellbeing.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/#primaryimage"},"image":{"@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2019\/06\/istockphoto-880860758-2048x2048.jpg","datePublished":"2019-06-21T07:12:28+00:00","dateModified":"2025-06-05T08:22:09+00:00","breadcrumb":{"@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/#primaryimage","url":"\/wp-content\/uploads\/2019\/06\/istockphoto-880860758-2048x2048.jpg","contentUrl":"\/wp-content\/uploads\/2019\/06\/istockphoto-880860758-2048x2048.jpg","width":1400,"height":932,"caption":"Alcoholism or drinking problem concept. Alcoholic with vodka bottle on table. Man and alcohol late at night. Drunk at work or in home office."},{"@type":"BreadcrumbList","@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/rapporti-con-collaboratori-a-rischio-di-dipendenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lyrawellbeing.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lyrawellbeing.ch\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Rapporti con i collaboratori a rischio di dipendenza"}]},{"@type":"WebSite","@id":"https:\/\/lyrawellbeing.ch\/#website","url":"https:\/\/lyrawellbeing.ch\/","name":"Lyra Schweiz GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyrawellbeing.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product\/3104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/media\/2253"}],"wp:attachment":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/media?parent=3104"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product_brand?post=3104"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product_cat?post=3104"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product_tag?post=3104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}