{"id":3120,"date":"2019-06-21T09:05:51","date_gmt":"2019-06-21T07:05:51","guid":{"rendered":"http:\/\/20.77.7.22\/shop\/senza%20categoria\/achtsamkeit\/"},"modified":"2025-06-05T10:09:53","modified_gmt":"2025-06-05T08:09:53","slug":"consapevolezza","status":"publish","type":"product","link":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/","title":{"rendered":"Consapevolezza"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>La consapevolezza \u00e8 uno stato d\u2019animo che focalizza sul presente, libero da ogni giudizio, che pu\u00f2 essere vissuto come fonte di creativit\u00e0, di pace e di serenit\u00e0. In questo corso si collegano la teoria sulla consapevolezza con allenamenti pratici, come la meditazione o esercizi di respirazione.<\/p>\n","protected":false},"featured_media":2229,"template":"","meta":[],"product_brand":[],"product_cat":[128],"product_tag":[],"class_list":{"0":"post-3120","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-prodotti-lyra-wellbeing-academy","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consapevolezza | Lyra Schweiz GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consapevolezza | Lyra Schweiz GmbH\" \/>\n<meta property=\"og:description\" content=\"La consapevolezza \u00e8 uno stato d\u2019animo che focalizza sul presente, libero da ogni giudizio, che pu\u00f2 essere vissuto come fonte di creativit\u00e0, di pace e di serenit\u00e0. In questo corso si collegano la teoria sulla consapevolezza con allenamenti pratici, come la meditazione o esercizi di respirazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyra Schweiz GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T08:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lyrawellbeing.ch\/wp-content\/uploads\/2019\/06\/istockphoto-950216224-2048x2048.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1755\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/\",\"url\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/\",\"name\":\"Consapevolezza | Lyra Schweiz GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyrawellbeing.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/istockphoto-950216224-2048x2048.jpg\",\"datePublished\":\"2019-06-21T07:05:51+00:00\",\"dateModified\":\"2025-06-05T08:09:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/#primaryimage\",\"url\":\"\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/istockphoto-950216224-2048x2048.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/istockphoto-950216224-2048x2048.jpg\",\"width\":1755,\"height\":1080,\"caption\":\"Creative thinking ideas brain innovation concept. Light bulb on yellow background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lyrawellbeing.ch\\\/it\\\/shop\\\/prodotti-lyra-wellbeing-academy\\\/consapevolezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lyrawellbeing.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lyrawellbeing.ch\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Consapevolezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyrawellbeing.ch\\\/#website\",\"url\":\"https:\\\/\\\/lyrawellbeing.ch\\\/\",\"name\":\"Lyra Schweiz GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyrawellbeing.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consapevolezza | Lyra Schweiz GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/","og_locale":"it_IT","og_type":"article","og_title":"Consapevolezza | Lyra Schweiz GmbH","og_description":"La consapevolezza \u00e8 uno stato d\u2019animo che focalizza sul presente, libero da ogni giudizio, che pu\u00f2 essere vissuto come fonte di creativit\u00e0, di pace e di serenit\u00e0. In questo corso si collegano la teoria sulla consapevolezza con allenamenti pratici, come la meditazione o esercizi di respirazione.","og_url":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/","og_site_name":"Lyra Schweiz GmbH","article_modified_time":"2025-06-05T08:09:53+00:00","og_image":[{"width":1755,"height":1080,"url":"https:\/\/www.lyrawellbeing.ch\/wp-content\/uploads\/2019\/06\/istockphoto-950216224-2048x2048.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/","url":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/","name":"Consapevolezza | Lyra Schweiz GmbH","isPartOf":{"@id":"https:\/\/lyrawellbeing.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/#primaryimage"},"image":{"@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2019\/06\/istockphoto-950216224-2048x2048.jpg","datePublished":"2019-06-21T07:05:51+00:00","dateModified":"2025-06-05T08:09:53+00:00","breadcrumb":{"@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/#primaryimage","url":"\/wp-content\/uploads\/2019\/06\/istockphoto-950216224-2048x2048.jpg","contentUrl":"\/wp-content\/uploads\/2019\/06\/istockphoto-950216224-2048x2048.jpg","width":1755,"height":1080,"caption":"Creative thinking ideas brain innovation concept. Light bulb on yellow background"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lyrawellbeing.ch\/it\/shop\/prodotti-lyra-wellbeing-academy\/consapevolezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lyrawellbeing.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lyrawellbeing.ch\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Consapevolezza"}]},{"@type":"WebSite","@id":"https:\/\/lyrawellbeing.ch\/#website","url":"https:\/\/lyrawellbeing.ch\/","name":"Lyra Schweiz GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyrawellbeing.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product\/3120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/media\/2229"}],"wp:attachment":[{"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/media?parent=3120"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product_brand?post=3120"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product_cat?post=3120"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lyrawellbeing.ch\/it\/wp-json\/wp\/v2\/product_tag?post=3120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}